{
    "id": 6845,
    "date": "2025-11-26T10:49:07",
    "date_gmt": "2025-11-26T10:49:07",
    "guid": {
        "rendered": "https:\/\/lemarelie.fr\/?p=6845"
    },
    "modified": "2025-11-26T10:49:08",
    "modified_gmt": "2025-11-26T10:49:08",
    "slug": "la-marelie-brotteaux-la-meilleure-creperie-au-coeur-de-lyon",
    "status": "publish",
    "type": "post",
    "link": "https:\/\/lemarelie.fr\/en\/blog\/la-marelie-brotteaux-la-meilleure-creperie-au-coeur-de-lyon\/",
    "title": {
        "rendered": "La Mar\u00e9lie Brotteaux : La meilleure cr\u00eaperie au c\u0153ur de Lyon"
    },
    "content": {
        "rendered": "<p>Vous recherchez la <strong>meilleure cr\u00eaperie au c\u0153ur de Lyon<\/strong>\u00a0? Ne cherchez plus \u2014 <strong><a href=\"https:\/\/lemarelie.fr\/fr\/\" title=\"\">La Mar\u00e9lie Brotteaux<\/a><\/strong>\u00a0est l\u2019endroit id\u00e9al pour savourer une exp\u00e9rience culinaire fran\u00e7aise authentique en famille, entre amis ou entre coll\u00e8gues.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Des sp\u00e9cialit\u00e9s bretonnes authentiques<\/strong><strong><\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9gustez de d\u00e9licieuses galettes sal\u00e9es et des cr\u00eapes sucr\u00e9es, pr\u00e9par\u00e9es \u00e0 la demande avec des ingr\u00e9dients locaux et de haute qualit\u00e9.<\/li>\n\n\n\n<li>Des classiques jambon-fromage aux cr\u00eapes au caramel beurre sal\u00e9, il y en a pour tous les go\u00fbts.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Une ambiance chaleureuse<\/strong><strong><\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Que vous soyez confortablement install\u00e9 dans notre int\u00e9rieur charmant ou install\u00e9 sur notre spacieuse terrasse, nous vous offrons une atmosph\u00e8re cosy et accueillante, parfaite pour toutes les occasions.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Id\u00e9al pour toutes les occasions<\/strong><strong><\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Repas en famille, \u00e9v\u00e9nements priv\u00e9s, r\u00e9servations de salle ou r\u00e9unions professionnelles \u2014 La Mar\u00e9lie Brotteaux, <strong>la meilleure cr\u00eaperie au c\u0153ur de Lyon<\/strong>, est le lieu parfait pour c\u00e9l\u00e9brer chaque moment.<\/li>\n\n\n\n<li>Nous proposons \u00e9galement des espaces de restauration privatisables pour rendre vos \u00e9v\u00e9nements encore plus sp\u00e9ciaux.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un emplacement privil\u00e9gi\u00e9<\/strong><strong><\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Situ\u00e9e dans le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Les_Brotteaux\" title=\"\">quartier des Brotteaux<\/a>, \u00e0 quelques minutes \u00e0 pied de la gare Part-Dieu, notre cr\u00eaperie est facile d\u2019acc\u00e8s, autant pour les Lyonnais que pour les visiteurs.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Des ingr\u00e9dients frais et locaux<\/strong><strong><\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nous sommes fiers de proposer une cuisine fran\u00e7aise authentique, pr\u00e9par\u00e9e avec des produits locaux venus de Bretagne et de la r\u00e9gion Rh\u00f4ne-Alpes.<\/li>\n\n\n\n<li>Chaque assiette servie \u00e0 La Mar\u00e9lie \u2014 <strong>la meilleure cr\u00eaperie au c\u0153ur de Lyon<\/strong>&nbsp;\u2014 est un v\u00e9ritable go\u00fbt de la France !<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pr\u00eat \u00e0 r\u00e9server votre table ?<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>Que vous souhaitiez un repas d\u00e9tente, organiser un \u00e9v\u00e9nement priv\u00e9 ou r\u00e9server une salle, <strong>La Mar\u00e9lie Brotteaux<\/strong>, <strong>la meilleure cr\u00eaperie au c\u0153ur de Lyon<\/strong>, est l\u2019adresse incontournable.<br><strong>R\u00e9servez d\u00e8s maintenant et d\u00e9couvrez l\u2019essence m\u00eame de la cuisine fran\u00e7aise \u00e0 Lyon !<\/strong><\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>Vous recherchez la meilleure cr\u00eaperie au c\u0153ur de Lyon\u00a0? Ne cherchez plus \u2014 La Mar\u00e9lie Brotteaux\u00a0est l\u2019endroit id\u00e9al pour savourer une exp\u00e9rience culinaire fran\u00e7aise authentique en famille, entre amis ou entre coll\u00e8gues. Des sp\u00e9cialit\u00e9s bretonnes authentiques Une ambiance chaleureuse Id\u00e9al pour toutes les occasions Un emplacement privil\u00e9gi\u00e9 Des ingr\u00e9dients frais et locaux Pr\u00eat \u00e0 r\u00e9server [&hellip;]<\/p>",
        "protected": false
    },
    "author": 2,
    "featured_media": 6846,
    "comment_status": "open",
    "ping_status": "open",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "footnotes": ""
    },
    "categories": [
        23
    ],
    "tags": [
        25,
        32,
        33,
        34,
        29,
        35,
        31,
        24,
        27,
        30,
        28,
        26
    ],
    "class_list": [
        "post-6845",
        "post",
        "type-post",
        "status-publish",
        "format-standard",
        "has-post-thumbnail",
        "hentry",
        "category-blog",
        "tag-authentic-breton-crepes-lyon",
        "tag-best-creperie-in-lyon",
        "tag-crepe-restaurant-brotteaux",
        "tag-creperie-lyon-center",
        "tag-creperie-near-part-dieu",
        "tag-family-friendly-creperie-lyon",
        "tag-french-cuisine-lyon",
        "tag-galettes-bretonnes-lyon",
        "tag-la-marelie-brotteaux",
        "tag-restaurant-brotteaux-lyon",
        "tag-traditional-french-creperie-lyon",
        "tag-where-to-eat-crepes-in-lyon"
    ],
    "aioseo_notices": [],
    "_links": {
        "self": [
            {
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/posts\/6845",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/users\/2"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/comments?post=6845"
            }
        ],
        "version-history": [
            {
                "count": 3,
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/posts\/6845\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 6853,
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/posts\/6845\/revisions\/6853"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/media\/6846"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/media?parent=6845"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/categories?post=6845"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/lemarelie.fr\/en\/wp-json\/wp\/v2\/tags?post=6845"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}